{"id":221751,"date":"2025-02-19T13:59:27","date_gmt":"2025-02-19T13:59:27","guid":{"rendered":"https:\/\/fr.wordpress.org\/plugins\/free-shipping-override\/"},"modified":"2025-08-10T11:33:28","modified_gmt":"2025-08-10T11:33:28","slug":"free-shipping-override","status":"publish","type":"plugin","link":"https:\/\/fy.wordpress.org\/plugins\/free-shipping-override\/","author":23172731,"comment_status":"closed","ping_status":"closed","template":"","meta":{"version":"1.0","stable_tag":"trunk","tested":"6.7.7","requires":"5.0","requires_php":"7.2","requires_plugins":null,"header_name":"Statistiques de vente : Analysez, optimisez, vendez plus","header_author":"Dynaweb","header_description":"Supprime les frais de livraison si certains produits, cat\u00e9gories sont pr\u00e9sents dans le panier ou si un montant minimum est atteint.","assets_banners_color":"","last_updated":"2025-08-10 11:33:28","external_support_url":"","external_repository_url":"","donate_link":"https:\/\/w-dynaweb.com\/","header_plugin_uri":"https:\/\/w-dynaweb.com","header_author_uri":"https:\/\/w-dynaweb.com","rating":0,"author_block_rating":0,"active_installs":0,"downloads":960,"num_ratings":0,"support_threads":0,"support_threads_resolved":0,"author_block_count":0,"sections":["description","installation","faq","changelog"],"tags":[],"upgrade_notice":[],"ratings":[],"assets_icons":{"icon-256x256.png":{"filename":"icon-256x256.png","revision":3344692,"resolution":"256x256","location":"assets","locale":"","width":496,"height":482}},"assets_banners":[],"assets_blueprints":{},"all_blocks":[],"tagged_versions":[],"block_files":[],"assets_screenshots":{"screenshot-2.png":{"filename":"screenshot-2.png","revision":3344692,"resolution":"2","location":"plugin","width":1920,"height":1080},"screenshot-3.jpg":{"filename":"screenshot-3.jpg","revision":3344692,"resolution":"3","location":"plugin","width":1920,"height":1080},"screenshot-4.png":{"filename":"screenshot-4.png","revision":3344692,"resolution":"4","location":"plugin","width":1920,"height":1080},"screenshot-1.jpg":{"filename":"screenshot-1.jpg","revision":3344692,"resolution":"1","location":"plugin","width":1920,"height":1080},"screenshot-3.png":{"filename":"screenshot-3.png","revision":3344692,"resolution":"3","location":"plugin","width":1920,"height":1080},"screenshot-4.jpg":{"filename":"screenshot-4.jpg","revision":3344692,"resolution":"4","location":"plugin","width":1920,"height":1080},"screenshot-2.jpg":{"filename":"screenshot-2.jpg","revision":3344692,"resolution":"2","location":"plugin","width":1920,"height":1080},"screenshot-1.png":{"filename":"screenshot-1.png","revision":3344692,"resolution":"1","location":"plugin","width":1920,"height":1080}},"screenshots":{"1":"Tableau de bord principal de Statistiques-de-vente.","2":"Statistiques d\u00e9taill\u00e9es des ventes par produit."}},"plugin_section":[],"plugin_tags":[4055,235408,235409,19064,286],"plugin_category":[45],"plugin_contributors":[235410],"plugin_business_model":[],"class_list":["post-221751","plugin","type-plugin","status-publish","hentry","plugin_tags-analyse","plugin_tags-commandes","plugin_tags-rapport","plugin_tags-statistiques","plugin_tags-woocommerce","plugin_category-ecommerce","plugin_contributors-dynaweb75","plugin_committers-dynaweb75"],"banners":[],"icons":{"svg":false,"icon":"https:\/\/ps.w.org\/free-shipping-override\/assets\/icon-256x256.png?rev=3344692","icon_2x":"https:\/\/ps.w.org\/free-shipping-override\/assets\/icon-256x256.png?rev=3344692","generated":false},"screenshots":[{"src":"https:\/\/ps.w.org\/free-shipping-override\/trunk\/screenshot-1.png?rev=3344692","caption":"Tableau de bord principal de Statistiques-de-vente."},{"src":"https:\/\/ps.w.org\/free-shipping-override\/trunk\/screenshot-2.png?rev=3344692","caption":"Statistiques d\u00e9taill\u00e9es des ventes par produit."},{"src":"https:\/\/ps.w.org\/free-shipping-override\/trunk\/screenshot-3.png?rev=3344692","caption":""},{"src":"https:\/\/ps.w.org\/free-shipping-override\/trunk\/screenshot-4.png?rev=3344692","caption":""}],"raw_content":"<!--section=description-->\n<p>Vous cherchez un moyen simple et puissant de comprendre les performances de votre boutique WooCommerce ? Avec Statistiques de vente, transformez vos donn\u00e9es en informations claires et pr\u00e9cises, le tout depuis une interface intuitive et simple \u00e0 utiliser.\nStatistiques-de-vente vous offre une vue d'ensemble compl\u00e8te de votre activit\u00e9. Que ce soit pour suivre vos revenus, analyser vos clients, ou identifier vos produits les plus performants, tout est pens\u00e9 pour vous offrir une vue d\u2019ensemble claire et organis\u00e9e.\nEn un clin d\u2019\u0153il, vous pouvez :\n\u2022 Suivre les tendances de votre boutique : Analysez vos ventes jour apr\u00e8s jour, rep\u00e9rez les p\u00e9riodes cl\u00e9s, et ajustez vos strat\u00e9gies pour maximiser vos r\u00e9sultats.\n\u2022 Mieux comprendre vos clients : Identifiez vos clients fid\u00e8les, vos nouveaux acheteurs et les comportements qui influencent leurs achats, tout en surveillant les abandons de panier.\n\u2022 Optimiser vos produits : D\u00e9couvrez vos best-sellers, am\u00e9liorez la visibilit\u00e9 de vos cat\u00e9gories les plus populaires, et identifiez les produits \u00e0 fort potentiel.\n\u2022 Mesurer l\u2019efficacit\u00e9 de vos promotions : \u00c9valuez l\u2019impact de vos remises et codes promo pour fid\u00e9liser votre client\u00e8le\nAvec Statistiques-de-vente, tout est simple. S\u00e9lectionnez une p\u00e9riode, cliquez sur \"Calculer\" et laissez le plugin g\u00e9n\u00e9rer des rapports d\u00e9taill\u00e9s et visuels organis\u00e9s en blocs faciles \u00e0 lire, pour vous offrir une vision claire et exploitable.\nPrenez le contr\u00f4le de votre boutique avec un outil con\u00e7u pour simplifier votre gestion et booster vos performances.\nEssayez Statistiques-de-vente d\u00e8s maintenant et faites parler vos donn\u00e9es\u202f!<\/p>\n\n<h3>Utilisation<\/h3>\n\n<ol>\n<li>Sur la page <strong>Statistiques de vente<\/strong>, s\u00e9lectionnez une p\u00e9riode de d\u00e9but et de fin.<\/li>\n<li>Cliquez sur <strong>Calculer<\/strong> pour g\u00e9n\u00e9rer les statistiques pour la p\u00e9riode s\u00e9lectionn\u00e9e.<\/li>\n<li>Les rapports incluent des m\u00e9triques comme la r\u00e9partition des commandes par pays, les revenus totaux, le montant moyen par commande, etc.<\/li>\n<\/ol>\n\n<h3>License<\/h3>\n\n<p>Ce plugin est distribu\u00e9 sous la licence GPLv2 ou ult\u00e9rieure. Certaines fonctionnalit\u00e9s avanc\u00e9es peuvent n\u00e9cessiter une version premium.<\/p>\n\n<h3>Documentation<\/h3>\n\n<p>Vous pouvez consulter la documentation compl\u00e8te du plugin ici : <a href=\"https:\/\/statistiques-de-vente.com\/a-propos\/\">https:\/\/statistiques-de-vente.com\/a-propos\/<\/a>.<\/p>\n\n<h3>Assets<\/h3>\n\n<p>Les images pour l'ic\u00f4ne et la banni\u00e8re sont automatiquement d\u00e9tect\u00e9es \u00e0 partir du dossier <code>assets<\/code>.<\/p>\n\n<!--section=installation-->\n<ol>\n<li>T\u00e9l\u00e9chargez le dossier du plugin.<\/li>\n<li>Extrayez-le, puis t\u00e9l\u00e9versez le dossier <code>advanced-statistics<\/code> dans le r\u00e9pertoire <code>\/wp-content\/plugins\/<\/code>.<\/li>\n<li>Activez le plugin via le menu \u00ab Extensions \u00bb de WordPress.<\/li>\n<li>Rendez-vous dans le menu <strong>Statistiques de vente<\/strong> pour consulter les rapports.<\/li>\n<\/ol>\n\n<!--section=faq-->\n<dl>\n<dt id='est-ce%20que%20le%20plugin%20est%20compatible%20avec%20toutes%20les%20versions%20de%20woocommerce%20%3F'><h3>Est-ce que le plugin est compatible avec toutes les versions de WooCommerce ?<\/h3><\/dt>\n<dd><p>Oui, le plugin est compatible avec WooCommerce 5.0 et versions ult\u00e9rieures.<\/p><\/dd>\n<dt id='comment%20puis-je%20personnaliser%20les%20rapports%20%3F'><h3>Comment puis-je personnaliser les rapports ?<\/h3><\/dt>\n<dd><p>Vous pouvez modifier les rapports en \u00e9ditant les fonctions du plugin dans <code>mon_plugin_stats_*<\/code>.<\/p><\/dd>\n<dt id='o%C3%B9%20puis-je%20obtenir%20de%20l%27aide%20si%20j%27ai%20des%20probl%C3%A8mes%20%3F'><h3>O\u00f9 puis-je obtenir de l'aide si j'ai des probl\u00e8mes ?<\/h3><\/dt>\n<dd><p>Vous pouvez nous contacter \u00e0 l'adresse e-mail suivante : contact@w-dynaweb.com.<\/p><\/dd>\n\n<\/dl>\n\n<!--section=changelog-->\n<h4>1.1.0<\/h4>\n\n<ul>\n<li>Version initiale.<\/li>\n<li>Statistiques de commandes, revenus par pays, taux d'abandon, et rapports d\u00e9taill\u00e9s des ventes.<\/li>\n<\/ul>","raw_excerpt":"Un plugin de statistiques avanc\u00e9es pour WooCommerce permettant d&#039;afficher diverses donn\u00e9es sur les commandes, les clients, et les produits.","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/fy.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin\/221751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fy.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin"}],"about":[{"href":"https:\/\/fy.wordpress.org\/plugins\/wp-json\/wp\/v2\/types\/plugin"}],"replies":[{"embeddable":true,"href":"https:\/\/fy.wordpress.org\/plugins\/wp-json\/wp\/v2\/comments?post=221751"}],"author":[{"embeddable":true,"href":"https:\/\/fy.wordpress.org\/plugins\/wp-json\/wporg\/v1\/users\/dynaweb75"}],"wp:attachment":[{"href":"https:\/\/fy.wordpress.org\/plugins\/wp-json\/wp\/v2\/media?parent=221751"}],"wp:term":[{"taxonomy":"plugin_section","embeddable":true,"href":"https:\/\/fy.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_section?post=221751"},{"taxonomy":"plugin_tags","embeddable":true,"href":"https:\/\/fy.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_tags?post=221751"},{"taxonomy":"plugin_category","embeddable":true,"href":"https:\/\/fy.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_category?post=221751"},{"taxonomy":"plugin_contributors","embeddable":true,"href":"https:\/\/fy.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_contributors?post=221751"},{"taxonomy":"plugin_business_model","embeddable":true,"href":"https:\/\/fy.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_business_model?post=221751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}